﻿{"id":27586,"date":"2025-08-13T11:40:47","date_gmt":"2025-08-13T11:40:47","guid":{"rendered":"https:\/\/pecb.com\/pecb-privacy-statement"},"modified":"2025-08-14T20:16:16","modified_gmt":"2025-08-14T20:16:16","slug":"pecb-privacy-statement","status":"publish","type":"page","link":"https:\/\/pecb.com\/fr\/pecb-privacy-statement","title":{"rendered":"D\u00e9claration de protection de la vie priv\u00e9e"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27586\" class=\"elementor elementor-27586 elementor-25180\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-103224c4 e-flex e-con-boxed e-con e-parent\" data-id=\"103224c4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cb2c617 elementor-widget elementor-widget-heading\" data-id=\"2cb2c617\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">D\u00e9claration de protection de la vie priv\u00e9e<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8629314 e-flex e-con-boxed e-con e-parent\" data-id=\"8629314\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdf2f02 elementor-widget elementor-widget-text-editor\" data-id=\"fdf2f02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p dir=\"auto\">\n        <style>\n            .child-pages {\n                display: flex;\n                flex-wrap: wrap;\n                justify-content: center;\n                gap: 8px;\n                width: fit-content;\n                margin: 0 auto;\n                 padding:10px;\n            }\n            .child-pages li {\n                display: flex;\n                padding: 8px 16px;\n                flex-direction: column;\n                align-items: center;\n                border-radius: 4px;\n                background: #FFF;\n                list-style: none;\n            }\n            .child-pages li.active {\n                background: #CBD5E1;\n            }\n            .child-pages li a {\n                color: #000;\n                text-align: center;\n                font-family: Parabolica, sans-serif;\n                font-size: 14px;\n                font-style: normal;\n                font-weight: 400;\n                line-height: normal;\n                text-decoration: none;\n            }\n            .child-pages li a:hover {\n                text-decoration: underline;\n            }\n        <\/style>\n    <ul class=\"child-pages\"><li class=\"\"><a href=\"https:\/\/pecb.com\/en\/about\">About<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/accreditations-and-affiliations\">Accr\u00e9ditations et Affiliations<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/code-of-ethics\">Code de d\u00e9ontologie<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/digital-trust\">Confiance num\u00e9rique : Construire un avenir s\u00fbr<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/statement-of-impartiality\">D\u00e9claration d\u2019impartialit\u00e9<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/gdpr-privacy-statement\">D\u00e9claration de protection de la vie priv\u00e9e RGPD<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/pecb-digital-badges\">PECB Digital Badges<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/team\">PECB Management<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/pecb-code-of-ethics-violation-policy\">Politique Applicable en cas de Violation du Code de D\u00e9ontologie de PECB<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/certification-mark-use-policy\">Politique d\u2019utilisation de la marque<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/pecb-policy-regarding-canadian-and-international-economic-sanctions-and-the-countries-impacted\">Politique de PECB relative aux sanctions \u00e9conomiques canadiennes et internationales et aux pays concern\u00e9s<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/pecb-refund-policy\">Politique de remboursement<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/complaint-and-appeal-policy\">Politique en mati\u00e8re de plainte et d\u2019appel<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/behavior-policy\">Politique relative aux comportements<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/pecb-quality-and-information-security-policies\">Politiques de qualit\u00e9 et de s\u00e9curit\u00e9 de l\u2019information<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/pecb-certification-process\">Processus de certification<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/values-of-pecb-certification\">Valeur de la certification PECB<\/a><\/li><li class=\"\"><a href=\"https:\/\/pecb.com\/fr\/about\/violation-of-pecb-brand-and-fraud-reporting-policy\">Violation de la marque PECB et de signalement des cas de fraude<\/a><\/li><\/ul><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6aed2473 e-flex e-con-boxed e-con e-parent\" data-id=\"6aed2473\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bdec577 elementor-widget elementor-widget-text-editor\" data-id=\"1bdec577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Derni\u00e8re mise \u00e0 jour le 16 septembre 2024.<\/p><h2><strong>1 Introduction<\/strong><\/h2><p>PECB respecte le droit \u00e0 la protection de la vie priv\u00e9e de chaque visiteur du site. Nous recueillons et utilisons l&rsquo;information de nos sites Web uniquement comme mentionn\u00e9 dans la pr\u00e9sente d\u00e9claration de protection de la vie priv\u00e9e. Cette d\u00e9claration de protection de la vie priv\u00e9e s\u2019applique uniquement \u00e0 ce site Web et divulgue les pratiques de protection des donn\u00e9es collect\u00e9es uniquement par\u00a0<a href=\"https:\/\/pecb.com\/fr\">PECB<\/a>. Si vous n&rsquo;\u00eates pas d&rsquo;accord avec une partie de cette d\u00e9claration, veuillez ne pas utiliser notre site Web.<\/p><p>Les termes \u00ab PECB \u00bb, \u00ab nous \u00bb et ses d\u00e9riv\u00e9s renvoient au propri\u00e9taire du site Web (\u00e9tabli au 336-6683 Jean-Talon Est, Montr\u00e9al (Qu\u00e9bec)\u00a0 H1S 0A5 Canada). Le terme \u00ab vous \u00bb et ses d\u00e9riv\u00e9s renvoient \u00e0 l&rsquo;utilisateur ou au visiteur de notre site Web. Le terme \u00ab d\u00e9claration \u00bb renvoie au pr\u00e9sent document. Les termes \u00ab site Web PECB \u00bb ou juste \u00ab site Web \u00bb renvoient aux sites Web\u00a0<a href=\"https:\/\/pecb.com\/\">https:\/\/pecb.com\/<\/a>,\u00a0<a href=\"https:\/\/insights.pecb.com\/\">https:\/\/insights.pecb.com\/<\/a>,\u00a0<a href=\"https:\/\/conference.pecb.com\/\">https:\/\/conference.pecb.com\/<\/a>,\u00a0<a href=\"https:\/\/store.pecb.com\/\">https:\/\/store.pecb.com\/<\/a>,\u00a0<a href=\"https:\/\/help.pecb.com\/\">https:\/\/help.pecb.com\/<\/a>,\u00a0<a href=\"https:\/\/mypecb.com\/\">https:\/\/mypecb.com\/<\/a>\u00a0et \u00e0 d\u2019autres domaines d\u00e9tenus et entretenus par PECB.<\/p><p>PECB est le responsable du traitement des donn\u00e9es que vous fournissez au cours des processus de demande, d&rsquo;inscription, de certification, d&rsquo;examen ou d&rsquo;autres objectifs d\u00e9crits dans la pr\u00e9sente d\u00e9claration de protection de la vie priv\u00e9e.<\/p><p>Toutes les donn\u00e9es que vous saisissez dans l&rsquo;un de nos formulaires en ligne seront stock\u00e9es \u00e9lectroniquement par PECB. Si vous avez des questions sur le processus ou la fa\u00e7on dont vos informations sont trait\u00e9es, veuillez contacter notre d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es par e-mail \u00e0 l\u2019adresse\u00a0<a href=\"mailto:information.security@pecb.com\">information.security@pecb.com<\/a>.<\/p><h2><strong>2 Contenu du site Web<\/strong><\/h2><p>Le contenu du site Web de PECB est prot\u00e9g\u00e9 par la loi sur la propri\u00e9t\u00e9 intellectuelle. Les informations et le contenu fournis ne peuvent \u00eatre r\u00e9utilis\u00e9s sans notre autorisation explicite, sauf pour un usage priv\u00e9 ou autre usage personnel au sens du R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD) Les communiqu\u00e9s de presse et les articles de notre service de presse pr\u00e9sent\u00e9s sur notre site Web sont \u00e0 la disposition des \u00e9diteurs de journaux ou de p\u00e9riodiques pour publication. S&rsquo;ils sont publi\u00e9s, nous demandons \u00e0 l&rsquo;\u00e9diteur de nous envoyer un exemplaire.\u00a0<\/p><p>Cette d\u00e9claration de protection de la vie priv\u00e9e ne couvre aucun des liens du site Web de PECB qui renvoie \u00e0 d&rsquo;autres sites Web non d\u00e9tenus ou g\u00e9r\u00e9s par PECB. Nous n&rsquo;avons aucune autorit\u00e9 ni aucune responsabilit\u00e9 sur le contenu ou la conception des sites Web d&rsquo;autres soci\u00e9t\u00e9s qui sont accessibles par des hyperliens \u00e0 partir de notre site Web. De plus, nous nous dissocions explicitement de tout contenu Internet qui pourrait \u00eatre ill\u00e9gal ou offensant. Vous assumez l&rsquo;enti\u00e8re responsabilit\u00e9 de l&rsquo;utilisation des hyperliens sur notre site Web pour acc\u00e9der aux sites Web d&rsquo;autres entreprises. Nous vous recommandons de v\u00e9rifier les politiques relatives \u00e0 la protection des donn\u00e9es et de la vie priv\u00e9e des partenaires de PECB ou des autres utilisateurs dont les sites Web sont accessibles \u00e0 partir de notre site.<\/p><p>PECB n&rsquo;est pas responsable des cons\u00e9quences li\u00e9es \u00e0 l&rsquo;ouverture ou \u00e0 l&rsquo;utilisation des sites Web de nos partenaires. Les hyperliens et adresses des partenaires fournis sur notre site Web sont g\u00e9n\u00e9r\u00e9s automatiquement (emplacement g\u00e9ographique et contact) suivant l\u2019adresse physique des partenaires.<\/p><h2><strong>3 Base l\u00e9gale du traitement<\/strong><\/h2><p>Nous recueillons des donn\u00e9es \u00e0 caract\u00e8re personnel (DCP) uniquement avec le consentement de la personne physique (la personne concern\u00e9e) et nous nous garantissons que les donn\u00e9es recueillies ne sont utilis\u00e9es qu&rsquo;aux fins indiqu\u00e9es.<\/p><p>En outre, lorsque vous cr\u00e9ez un compte et devenez un client, un partenaire, un formateur, un surveillant ou un distributeur de PECB, vous devez remplir un formulaire \u00e9lectronique pour lequel nous ne sommes pas responsables.\u00a0 Nous vous demandons votre consentement pour vous envoyer de l&rsquo;information uniquement en ce qui concerne nos formations, nouvelles, newsletters, webinaires ou tout autre contenu li\u00e9 \u00e0 nos services.<\/p><h2><strong>4 Type de donn\u00e9es collect\u00e9es<\/strong><\/h2><p>Nous ne recueillons que les donn\u00e9es que vous nous fournissez lorsque vous visitez notre site Web.<\/p><p>La transmission d&rsquo;informations \u00e0 PECB est un acte volontaire. Le fait de cliquer sur le bouton \u00ab Soumettre \u00bb\u00a0 de l&rsquo;un des formulaires de notre site web signifie que vous \u00eates au courant des\u00a0<a href=\"https:\/\/pecb.com\/fr\/terms-conditions-and-policies\">Conditions d\u2019utilisation du site Web de PECB<\/a>\u00a0et que vous consentez volontairement aux conditions qui y sont \u00e9nonc\u00e9es<\/p><h3><strong>4.1 Formulaires d&rsquo;inscription<\/strong><\/h3><p>Lorsque vous cr\u00e9ez un compte PECB, vous nous fournissez des donn\u00e9es qui peuvent vous identifier personnellement, telles que vos nom complet, adresse e-mail, num\u00e9ro de t\u00e9l\u00e9phone, pays, r\u00e9gion et ville. Par ailleurs, lorsque vous cr\u00e9ez un compte de partenaire PECB, nous recueillons \u00e9galement des donn\u00e9es sur votre soci\u00e9t\u00e9, notamment son nom, son adresse physique, son num\u00e9ro de t\u00e9l\u00e9phone. Les informations sur les prospects des partenaires sont \u00e9galement sous-trait\u00e9es dans HubSpot. Pour plus d\u2019informations sur la mani\u00e8re dont les donn\u00e9es sont trait\u00e9es par ces derniers, veuillez lire la\u00a0<a href=\"https:\/\/legal.hubspot.com\/privacy-policy\">Politique de confidentialit\u00e9 de HubSpot<\/a>.<\/p><p>Les donn\u00e9es que nous recueillons nous aident \u00e0 compl\u00e9ter votre processus d&rsquo;inscription et \u00e0 vous identifier en tant qu&rsquo;utilisateur de notre site Web.<\/p><h3><strong>4.2 Inscription \u00e0 partir du site du partenaire<\/strong><\/h3><p>PECB op\u00e8re dans le monde \u00e0 travers son r\u00e9seau de partenaires. PECB aide ses partenaires pour qu&rsquo;ils puissent ex\u00e9cuter et offrir les services de PECB \u00e0 leurs clients de mani\u00e8re efficace et de qualit\u00e9 sup\u00e9rieure. Les partenaires PECB sont autoris\u00e9s \u00e0 cr\u00e9er des sessions de formation et \u00e0 y inscrire des participants \u00e0 une formation. En utilisant le formulaire\u00a0<em>Inscrire des participants \u00e0 une formation<\/em>, le compte PECB d\u2019un participant sera cr\u00e9\u00e9 par le partenaire et ne sera activ\u00e9 que lorsque l\u2019utilisateur aura cliqu\u00e9 sur le lien d&rsquo;activation envoy\u00e9 par e-mail.<\/p><p>Le partenaire est enti\u00e8rement responsable de la cr\u00e9ation du compte et de l&rsquo;utilisation des DCP du participant, notamment les nom complet, pays, r\u00e9gion et adresse e-mail.<\/p><h3><strong>4.3 E-mails de marketing<\/strong><\/h3><p>PECB Group Inc. est le responsable du traitement des donn\u00e9es pour toutes les communications marketing des services et produits de PECB, incluant :<\/p><ul><li>PECB Inc. ;<\/li><li>PECB Store ;<\/li><li>PECB Insights Magazine ;<\/li><li>PECB Conference.<\/li><\/ul><p>Si vous avez pr\u00e9alablement accept\u00e9 de recevoir des communications marketing, vous recevrez occasionnellement des nouvelles et des offres pertinentes sur nos services et produits. Afin d&rsquo;am\u00e9liorer nos services, nous pourrions vous contacter dans le cadre de sondages et d&rsquo;\u00e9tudes de march\u00e9.<\/p><p>Les informations personnelles collect\u00e9es \u00e0 des fins de marketing sont trait\u00e9es conform\u00e9ment \u00e0 vos pr\u00e9f\u00e9rences d&rsquo;abonnement.<\/p><h3><strong>4.4 Centre d&rsquo;aide<\/strong><\/h3><p>Nos clients b\u00e9n\u00e9ficient de l\u2019assistance du chatbot HubSpot, disponible dans le centre d\u2019aide de notre site Web. Votre nom, votre e-mail et le contenu de la messagerie instantan\u00e9e seront recueillis si vous utilisez notre chatbot. Nous ne conserverons ces informations que pendant trois ans et nous ne les partagerons avec une tierce personne. Nous surveillons en permanence les journaux de messagerie instantan\u00e9e afin d\u2019am\u00e9liorer la qualit\u00e9.<\/p><p>Lorsque vous appelez la ligne d&rsquo;assistance de PECB, nous recueillons des donn\u00e9es d&rsquo;identification de la ligne appelante. Nous utilisons ces donn\u00e9es pour am\u00e9liorer l&rsquo;efficience et l&rsquo;efficacit\u00e9 de nos services. PECB conserve les donn\u00e9es n\u00e9cessaires pour r\u00e9pondre aux demandes des appelants, en ouvrant un ticket dans le syst\u00e8me, et en suivant les processus concernant le ticket jusqu&rsquo;\u00e0 la fin de la proc\u00e9dure. Les donn\u00e9es fournies par le syst\u00e8me de ticket sont examin\u00e9es et, le cas \u00e9ch\u00e9ant, supprim\u00e9es chaque ann\u00e9e.<\/p><h3><strong>4.5 Personnes qui contactent notre r\u00e9seau par le site Web<\/strong><\/h3><p>Si vous utilisez notre site Web pour vous connecter \u00e0 notre r\u00e9seau de partenaires et de formateurs, nous ne recueillerons que les donn\u00e9es que vous nous fournirez, notamment vos nom, num\u00e9ro de t\u00e9l\u00e9phone, adresse e-mail, lieu de r\u00e9sidence.\u00a0<\/p><p>Votre message compos\u00e9 est \u00e9galement recueilli pour pr\u00e9venir, d\u00e9tecter et r\u00e9pondre \u00e0 toute forme de fraude ou d&rsquo;abus qui pourrait nuire \u00e0 notre r\u00e9seau.<\/p><h3><strong>4.6 Candidats \u00e0 l&#8217;emploi<\/strong><\/h3><p>Lorsque vous postulez \u00e0 un poste chez PECB, nous vous demandons des donn\u00e9es personnelles : vos coordonn\u00e9es, votre adresse e-mail et votre CV. Votre CV peut contenir d&rsquo;autres donn\u00e9es consid\u00e9r\u00e9es comme des donn\u00e9es personnelles, telles que vos dipl\u00f4mes, votre formation professionnelle et vos exp\u00e9riences professionnelles ant\u00e9rieures.<\/p><p>Toutes les donn\u00e9es que vous fournissez au cours du processus de demande d&#8217;emploi ne sont utilis\u00e9es que dans le but de traiter votre demande ou de satisfaire aux exigences l\u00e9gales et r\u00e9glementaires si n\u00e9cessaire. Nous utilisons vos coordonn\u00e9es pour vous fournir des informations relatives au traitement de votre demande d&#8217;emploi. Nous utilisons les autres informations que vous nous fournissez pour \u00e9valuer votre aptitude \u00e0 occuper le poste pour lequel vous avez postul\u00e9.<\/p><p>Nous ne recueillons que les informations n\u00e9cessaires pour atteindre nos objectifs et ne conservons aucune donn\u00e9e plus longtemps que n\u00e9cessaire. Nous ne partageons avec aucun tiers les informations que vous nous fournissez. Les donn\u00e9es que vous fournissez, qu&rsquo;elles soient digitales ou physiques, seront trait\u00e9es en toute s\u00e9curit\u00e9.<\/p><h3><strong>4.7 PECB Connect<\/strong><\/h3><p>Dans le cadre de notre engagement \u00e0 maintenir un niveau \u00e9lev\u00e9 d&rsquo;int\u00e9grit\u00e9 et de professionnalisme, les personnes souhaitant devenir auditeurs sur la plateforme PECB Connect seront soumises \u00e0 un processus de s\u00e9lection. Cette s\u00e9lection, effectu\u00e9e par nos partenaires de confiance, Sterling et Triton, comprendra une v\u00e9rification du parcours acad\u00e9mique du candidat et une v\u00e9rification de ses ant\u00e9c\u00e9dents criminels. Apr\u00e8s avoir d\u00e9pos\u00e9 une demande sur la plateforme PECB Connect, le candidat recevra un e-mail de Sterling et\/ou de Triton l&rsquo;invitant \u00e0 consentir \u00e0 la v\u00e9rification de ses ant\u00e9c\u00e9dents. Ces mesures sont mises en \u0153uvre pour garantir la fiabilit\u00e9 et la cr\u00e9dibilit\u00e9 des auditeurs associ\u00e9s \u00e0 PECB Connect.<\/p><p>Toutes les donn\u00e9es \u00e0 caract\u00e8re personnel collect\u00e9es au cours du processus de s\u00e9lection seront trait\u00e9es conform\u00e9ment \u00e0 notre politique de protection de la vie priv\u00e9e et aux lois applicables en mati\u00e8re de protection des donn\u00e9es. Pour plus d&rsquo;informations sur la mani\u00e8re dont Sterling et Triton traitent les donn\u00e9es, cliquez ici.<a href=\"https:\/\/privacy.sterlingcheck.com\/\">Principes de base de la protection de la vie priv\u00e9e &#8211; Sterling Privacy (sterlingcheck.com)<\/a>,\u00a0<a href=\"https:\/\/www.tritoncanada.ca\/triton-privacy-policy\/\">Politique de confidentialit\u00e9 de Triton (tritoncanada.ca)<\/a>.<\/p><h3><strong>4.8 S\u00e9lection et suivi des sanctions \u00e9conomiques internationales<\/strong><\/h3><p>Nous utilisons ComplyAdvantage pour filtrer et contr\u00f4ler les nouveaux utilisateurs et ceux qui existent d\u00e9j\u00e0, y compris les organisations, par rapport aux sanctions \u00e9conomiques internationales o\u00f9 PECB est pr\u00e9sent ou op\u00e8re, y compris l&rsquo;ONU, les sanctions \u00e9conomiques canadiennes, les \u00c9tats-Unis, l&rsquo;UE et la Malaisie, ainsi que les sanctions des pays o\u00f9 sont bas\u00e9es les autorit\u00e9s d&rsquo;accr\u00e9ditation. Des informations telles que le nom, l&rsquo;ann\u00e9e de naissance et le pays sont n\u00e9cessaires pour v\u00e9rifier et contr\u00f4ler les listes de sanctions.<\/p><p>Si vous donnez votre consentement au traitement des donn\u00e9es susmentionn\u00e9es lors de la cr\u00e9ation de votre compte PECB, le service examinera et contr\u00f4lera automatiquement vos informations par rapport aux listes de sanctions. Pour conna\u00eetre vos droits en tant que personne concern\u00e9e et savoir comment ComplyAdvantage traite vos informations, veuillez consulter\u00a0<a href=\"https:\/\/complyadvantage.com\/privacy-notice\/\">la Politique de protection de la vie priv\u00e9e de ComplyAdvantage<\/a>.<\/p><h2><strong>5 Nos prestataires de services<\/strong><\/h2><h3><strong>5.1 Amazon Web Services<\/strong><\/h3><p>Pour fournir nos services et publier notre\u00a0<a href=\"https:\/\/pecb.com\/\">site Web<\/a>, nous utilisons la plateforme de cloud computing d&rsquo;<em>Amazon Web Services (AWS)<\/em>. Les donn\u00e9es sont transf\u00e9r\u00e9es vers les serveurs d&rsquo;AWS situ\u00e9s en Virginie du Nord, aux \u00c9tats-Unis, afin de fournir des services. Afin de garantir la conformit\u00e9 avec le RGPD pour le transfert de donn\u00e9es en dehors de l&rsquo;Union europ\u00e9enne, AWS participe au cadre de confidentialit\u00e9 des donn\u00e9es UE-\u00c9tats-Unis. Nous n&rsquo;accordons aucune autorisation \u00e0 AWS de partager les donn\u00e9es personnelles que nous recueillons aupr\u00e8s des titulaires de comptes de notre site Web. Nous utilisons AWS, car il est conforme \u00e0 plusieurs des exigences en mati\u00e8re de s\u00e9curit\u00e9 de l&rsquo;information, notamment, mais sans exclure d\u2019autres exigences, les normes ISO\/IEC 27001, ISO\/IEC 27701 et le R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es de l&rsquo;UE.\u00a0 Vous pouvez lire l\u2019avis de protection des donn\u00e9es d&rsquo;AWS\u00a0<a href=\"https:\/\/aws.amazon.com\/fr\/privacy\/?nc1=h_ls%20\">ici<\/a>.<\/p><h3><strong>5.2 Courrier \u00e9lectronique<\/strong><\/h3><p><em>Microsoft 365 (Outlook)<\/em>\u00a0est un autre service que nous utilisons pour l&rsquo;\u00e9change d&rsquo;e-mails et la sauvegarde des donn\u00e9es dans le cloud. Nous utilisons\u00a0<em>Microsoft 365,<\/em>\u00a0car il est conforme \u00e0 plusieurs des exigences en mati\u00e8re de s\u00e9curit\u00e9 de l&rsquo;information, notamment, mais sans exclure d\u2019autres exigences, les normes ISO\/IEC 27001, ISO\/IEC 27701 et le R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es de l&rsquo;UE.\u00a0<em>Microsoft 365<\/em>\u00a0offre un chiffrement des donn\u00e9es inactives qui inclut les fichiers stock\u00e9s dans le service cloud et un chiffrement des donn\u00e9es en transit qui inclut les messages e-mail \u00e9chang\u00e9s ou les conversations qui ont lieu lors d&rsquo;une r\u00e9union.<\/p><p><em>Microsoft 365<\/em>\u00a0utilise plusieurs technologies et protocoles de chiffrement puissants, notamment Internet Protocol Security (IPSec), Transport Layer Security\/Secure Sockets Layer (TLS\/SSL) et Advanced Encryption Standard (AES). Nous ne garantissons pas le chiffrement aux destinataires de nos e-mails. Par cons\u00e9quent, il est de votre responsabilit\u00e9 de veiller au chiffrement de vos messages.<\/p><p>Nous contr\u00f4lons \u00e9galement tous les courriels qui nous sont envoy\u00e9s pour d\u00e9tecter les virus ou les logiciels malveillants, y compris les pi\u00e8ces jointes. Notez que vous avez la responsabilit\u00e9 de vous assurer que tout courriel que vous nous envoyez est conforme \u00e0 la loi.<\/p><p>Nous faisons appel \u00e0 des tiers tels que\u00a0<em>Sendinblue, Amazon SES, Hubspot et Microsoft Outlook<\/em>, pour l\u2019envoi des e-mails \u00e0 notre r\u00e9seau. Pour plus d\u2019informations sur la fa\u00e7on dont les donn\u00e9es sont trait\u00e9es par ces tiers, veuillez lire les politiques suivantes :\u00a0<a href=\"https:\/\/www.sendinblue.com\/legal\/privacypolicy\/\">Politique de protection de la vie priv\u00e9e de Sendinblue<\/a>,\u00a0<a href=\"https:\/\/aws.amazon.com\/fr\/privacy\/?nc1=h_ls\">Avis concernant la protection des donn\u00e9es\u00a0<em>d\u2019Amazon<\/em><\/a>,\u00a0<a href=\"https:\/\/legal.hubspot.com\/privacy-policy\">Politique de confidentialit\u00e9 de HubSpot<\/a>\u00a0et\u00a0<a href=\"https:\/\/privacy.microsoft.com\/en-us\/privacystatement\">D\u00e9claration de confidentialit\u00e9 de Microsoft<\/a>.<\/p><h3><strong>5.3 Paiements sur le site Web de PECB<\/strong><\/h3><p>Les paiements effectu\u00e9s \u00e0 partir du site Web de PECB sont trait\u00e9s par un service tiers appel\u00e9 Stripe. Les donn\u00e9es fournies lors du processus de paiement ne sont pas stock\u00e9es dans le syst\u00e8me PECB et elles sont transmises \u00e0\u00a0<em>Stripe\u00a0<\/em>dans le seul but de compl\u00e9ter le processus de paiement initi\u00e9 par l&rsquo;utilisateur. Pour savoir comment\u00a0<em>Stripe\u00a0<\/em>traite et utilise vos donn\u00e9es, veuillez lire leur\u00a0<a href=\"https:\/\/stripe.com\/privacy\">Politique de confidentialit\u00e9<\/a>.<\/p><p>Notre site Web prend \u00e9galement en charge les services de paiement PayPal. La d\u00e9claration de protection de la vie priv\u00e9e de PayPal est disponible\u00a0<a href=\"https:\/\/www.paypal.com\/al\/webapps\/mpp\/ua\/privacy-full\">ici<\/a>.<\/p><h3><strong>5.4 Lockstep Collect<\/strong><\/h3><p>Nous utilisons Lockstep Collect, un service de comptabilit\u00e9 automatis\u00e9 pour g\u00e9rer notre processus de recouvrement de cr\u00e9ances. Les coordonn\u00e9es de nos clients (participants), et parfois les factures, sont stock\u00e9es dans l&rsquo;application. Gr\u00e2ce \u00e0 un processus automatis\u00e9, l&rsquo;application communiquera des notifications aux clients qui ont des factures en souffrance aupr\u00e8s de PECB.<\/p><p>La Politique de protection de la vie priv\u00e9e de Lockstep Collect est disponible\u00a0<a href=\"https:\/\/lockstep.io\/privacy\/\">ici<\/a>.<\/p><h3><strong>5.5 GoToWebinar<\/strong><\/h3><p>Pour que nos webinaires gratuits soient accessibles mondialement, nous utilisons les services de LogMeIn Inc, GoToWebinar et GoToMeeting. Go-To-Webinar se conforme au cadre de protection des donn\u00e9es de l&rsquo;UE et des \u00c9tats-Unis. La politique de confidentialit\u00e9 de LogMeIn Inc. est disponible\u00a0<a href=\"https:\/\/www.logmeininc.com\/trust\/privacy\">ici<\/a>.<\/p><p>Lorsque vous souhaitez participer \u00e0 un webinaire organis\u00e9 par PECB, lors de l&rsquo;inscription sur la plateforme, nous recueillons vos nom complet, adresse e-mail et lieu de r\u00e9sidence dans le seul but d&rsquo;identifier votre participation au webinaire.<\/p><h3><strong>5.6 R\u00e9seaux sociaux<\/strong><\/h3><p>Nous utilisons des fournisseurs tiers, entre autres\u00a0<em>LinkedIn, Facebook, Instagram, Twitter, YouTube, SlideShare, ISSUU, Pinterest<\/em>, pour g\u00e9rer nos interactions avec les r\u00e9seaux sociaux.<\/p><p>L&rsquo;interaction avec les r\u00e9seaux sociaux est assur\u00e9e par les comptes de r\u00e9seaux sociaux \u00e9num\u00e9r\u00e9s ci-dessus. Tous les prestataires ont leur propre politique de protection de la vie priv\u00e9e qui d\u00e9crit la mani\u00e8re dont ils recueillent, traitent et stockent les donn\u00e9es. Pour lire leurs politiques et d\u00e9clarations, veuillez visiter leur site Web.<\/p><p>Si vous nous envoyez un message priv\u00e9 ou direct sur les r\u00e9seaux sociaux, le message sera stock\u00e9 sur LinkedIn et SlideShare, conform\u00e9ment \u00e0 leur\u00a0<a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\">Politique de protection de la vie priv\u00e9e<\/a>, sur Facebook et Instagram conform\u00e9ment \u00e0 leur\u00a0<a href=\"https:\/\/www.facebook.com\/privacy\/explanation\">Politique de protection des donn\u00e9es<\/a>\u00a0ou sur\u00a0<em>Twitter\u00a0<\/em>conform\u00e9ment \u00e0 leur\u00a0<a href=\"https:\/\/twitter.com\/en\/privacy\">Politique de protection de la vie priv\u00e9e<\/a>.\u00a0<em>Google LLC<\/em>\u00a0et ses soci\u00e9t\u00e9s affili\u00e9es offrent diff\u00e9rents services, dont YouTube, pour lesquels ils ont leur propre\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=en-US\">politique de protection de la vie priv\u00e9e<\/a>.<\/p><p>Les abonn\u00e9s au compte\u00a0<em>LinkedIn\u00a0<\/em>de PECB ne seront pas partag\u00e9s avec un autre r\u00e9seau par PECB \u00e0 moins que les abonn\u00e9s ne le demandent. Nous n&rsquo;envoyons pas de communications commerciales aux abonn\u00e9s de notre r\u00e9seau sans consentement pr\u00e9alable. Par ailleurs, nous pourrions publier un lien pour s&rsquo;abonner \u00e0 nos publications et bulletins d\u2019information.<\/p><h3><strong>5.7 Badges num\u00e9riques<\/strong><\/h3><p>Nous utilisons Credly pour d\u00e9livrer des badges num\u00e9riques qui sont des versions Web de vos certifications.\u00a0 Les informations telles que votre nom, votre adresse \u00e9lectronique et vos programmes de certification sont n\u00e9cessaires pour assurer l\u2019authentification des badges par Credly.\u00a0\u00a0<\/p><p>En donnant votre consentement au traitement des donn\u00e9es susmentionn\u00e9es lors de la cr\u00e9ation de votre compte PECB, et apr\u00e8s la cr\u00e9ation d\u2019un compte avec Credly, le service attribuera automatiquement des badges suivant la validation de votre demande de certification.\u00a0 Pour conna\u00eetre vos droits en tant que personne concern\u00e9e et savoir comment Credly traite vos informations, veuillez consulter la\u00a0<a href=\"https:\/\/www.credly.com\/privacy\">Politique de protection de la vie priv\u00e9e de Credly<\/a>.<\/p><h3><strong>5.8 Syst\u00e8me de ticket<\/strong><\/h3><p>Pour d\u00e9celer les probl\u00e8mes et g\u00e9rer les projets, nous utilisons les services de gestion d\u2019Atlassian Jira et HubSpot.<\/p><p>Nous pouvons stocker les donn\u00e9es personnelles des personnes lorsque cela est n\u00e9cessaire pour suivre et g\u00e9rer les questions relatives \u00e0 leur compte ou au syst\u00e8me PECB.\u00a0 Le contenu peut \u00e9galement inclure une description du sujet, des fichiers et des liens pertinents au sujet. Pour conna\u00eetre vos droits des personnes concern\u00e9es et savoir comment Atlassian Jira et HubSpot traitent vos informations, veuillez consulter la\u00a0<a href=\"https:\/\/www.atlassian.com\/legal\/privacy-policy\">Politique de confidentialit\u00e9<\/a>\u00a0d\u2019Atlassian Jira et la\u00a0<a href=\"https:\/\/legal.hubspot.com\/privacy-policy\">Politique de confidentialit\u00e9 de HubSpot<\/a>.<\/p><h3><strong>5.9 Zapier, Inc.<\/strong><\/h3><p>Pour inscrire les participants \u00e0 nos webinaires et automatiser les pr\u00e9f\u00e9rences d&rsquo;e-mails, nous utilisons Zapier Inc. Zapier peut stocker les donn\u00e9es personnelles n\u00e9cessaires \u00e0 la gestion des participants aux webinaires et \u00e0 l&rsquo;automatisation des pr\u00e9f\u00e9rences d&rsquo;abonnement aux e-mails. Ces informations sont transf\u00e9r\u00e9es \u00e0 Zapier situ\u00e9 aux \u00c9tats-Unis. Zapier respecte le cadre de protection des donn\u00e9es UE-\u00c9tats-Unis. Pour plus d\u2019informations sur le mode de traitement des donn\u00e9es par Zapier, veuillez consulter la\u00a0<a href=\"https:\/\/zapier.com\/privacy\">Politique en mati\u00e8re de protection de lavie priv\u00e9e de Zapier<\/a><\/p><h2><strong>6 Cookies et technologies similaires<\/strong><\/h2><p>Lorsque vous visitez notre site Web, vous devez savoir que nous utilisons des services de tierces parties comme\u00a0<em>Google Analytics<\/em>\u00a0pour recueillir des informations standard de journalisation Internet et les d\u00e9tails des mod\u00e8les de comportement des visiteurs. Cette op\u00e9ration est effectu\u00e9e dans le but de recueillir des informations sur le nombre de visiteurs de notre site Web. Le traitement de ces donn\u00e9es ne fournit aucune donn\u00e9e permettant d&rsquo;identifier les visiteurs.<\/p><p>De plus, nous utilisons un r\u00e9seau de diffusion de contenu pour g\u00e9olocaliser les visiteurs de notre site Web. Le seul cas o\u00f9 PECB recueille des donn\u00e9es \u00e0 caract\u00e8re personnel par l&rsquo;entremise du site Web est lorsqu&rsquo;un visiteur cr\u00e9e volontairement un compte utilisateur. Nous assurons une transparence totale et fournissons des explications claires sur la mani\u00e8re dont nous utilisons les informations recueillies dans ces cas.<\/p><p>Vous pouvez en lire plus sur la fa\u00e7on dont nous utilisons les cookies dans notre\u00a0<a href=\"https:\/\/pecb.com\/cookie-policy\">Politique relative aux cookies<\/a>.<\/p><h2><strong>7 Examen de certification<\/strong><\/h2><p>Lors de l&rsquo;inscription \u00e0 un examen en ligne, les candidats doivent pr\u00e9senter leur pi\u00e8ce d&rsquo;identit\u00e9 gouvernementale ou non gouvernementale au surveillant. Celui-ci compare la pi\u00e8ce avec le visage du candidat via un flux vid\u00e9o en direct. Si le flux de cam\u00e9ra du candidat n\u2019est pas assez clair, le candidat devra t\u00e9l\u00e9charger une photo de sa carte d\u2019identit\u00e9 sur l\u2019application. Pour ce faire, il doit avoir une image JPEG\/PNG ou PDF de la pi\u00e8ce d&rsquo;identit\u00e9 avant d&rsquo;int\u00e9grer la session en ligne.\u00a0<\/p><p>REMARQUE IMPORTANTE : Le document t\u00e9l\u00e9charg\u00e9 ne sera pas sauvegard\u00e9 et sera automatiquement effac\u00e9 une fois l\u2019examen termin\u00e9.<\/p><p>En plus de la pi\u00e8ce d&rsquo;identit\u00e9, les candidats doivent indiquer s&rsquo;ils sont natif de la langue de l&rsquo;examen, ajouter des informations sur une personne \u00e0 contacter en cas d&rsquo;urgence, la relation avec cette personne et le num\u00e9ro de t\u00e9l\u00e9phone de cette derni\u00e8re. Ces informations sont cruciales pour notifier au plus vite ce tiers et obtenir de lui une r\u00e9ponse rapide au cas o\u00f9 un candidat \u00e0 un examen en ligne aurait une urgence m\u00e9dicale.<\/p><p>Les candidats qui passent l&rsquo;examen sur papier doivent remplir la Feuille d&rsquo;identification du candidat (CISH) avant de commencer l&rsquo;examen. Dans la CISH, ils doivent fournir leur nom complet, leur adresse \u00e9lectronique et des d\u00e9tails suppl\u00e9mentaires sur la s\u00e9ance d&rsquo;examen, comme le titre de l&rsquo;examen, la date et le lieu. La collecte de ces informations a pour seul but de permettre \u00e0 PECB d&rsquo;identifier les candidats.<\/p><p>PECB utilisera votre nom complet et votre adresse e-mail pour vous inscrire dans le syst\u00e8me de traitement des examens. En outre, nous pourrions \u00e9galement utiliser votre nom complet et votre adresse e-mail pour vous inscrire \u00e0 session de formation, si cette \u00e9tape n\u2019a pas d\u00e9j\u00e0 \u00e9t\u00e9 compl\u00e9t\u00e9e par le Partenaire PECB.\u00a0<\/p><p>Les formations PECB sont offertes par des partenaires agr\u00e9\u00e9s par PECB. Apr\u00e8s avoir termin\u00e9 la formation, les candidats peuvent passer l&rsquo;examen de certification sur papier ou par le biais de la plateforme d&rsquo;examen en ligne de PECB. La date de l\u2019annonce des r\u00e9sultats de l\u2019examen d\u00e9pend de plusieurs facteurs. Apr\u00e8s l\u2019annonce des r\u00e9sultats de l\u2019examen, l\u2019organisateur de la formation (partenaire PECB) et le formateur (formateur certifi\u00e9 par PECB) pourront voir les r\u00e9sultats d\u2019examen afin d\u2019accomplir des t\u00e2ches administratives (p. ex., compl\u00e9ter la liste des candidats, programmer les reprises d\u2019examen). Ceci s&rsquo;applique \u00e0 tous les participants qui, apr\u00e8s avoir suivi la formation, font leur premier essai \u00e0 un examen papier, reprennent un examen papier, font un premier essai \u00e0 un examen en ligne, ou reprennent un examen en ligne.<\/p><p>Ceci s\u2019applique \u00e0 tous les formats de formation propos\u00e9s par PECB \u00e0 travers ses partenaires agr\u00e9\u00e9s. Les r\u00e9sultats sont transmis aux partenaires et aux formateurs \u00e0 travers le compte de leur partenaire et du ou des compte(s) de formateurs.<\/p><p>Si, en raison d&rsquo;un handicap, un candidat a besoin de mesures d&rsquo;adaptation sp\u00e9ciales pendant l&rsquo;examen, il doit remplir le\u00a0<a href=\"https:\/\/pecb.com\/pdf\/pecb-402-ada_form-fr.pdf\">Formulaire pour les candidats pr\u00e9sentant un handicap<\/a>\u00a0et fournir \u00e0 PECB la documentation n\u00e9cessaire afin que la demande soit examin\u00e9e pour approbation. Les informations relatives \u00e0 l&rsquo;\u00e9tat de sant\u00e9 du candidat sont trait\u00e9es de mani\u00e8re strictement confidentielle et sont supprim\u00e9es des donn\u00e9es de candidature apr\u00e8s une p\u00e9riode de six mois.<\/p><h3><strong>7.1 PECB Exams<\/strong><\/h3><p>PECB Exams, l&rsquo;application que nous avons d\u00e9velopp\u00e9e pour offrir des examens de certification en ligne, est \u00e9galement utilis\u00e9e pour fournir des examens de certification pour les programmes de certification PECB accr\u00e9dit\u00e9s par l&rsquo;IAS.<\/p><p>L&rsquo;application partage le flux de la webcam et l&rsquo;\u00e9cran de l&rsquo;ordinateur du candidat, et non pas simultan\u00e9ment, avec le surveillant d&rsquo;examen en ligne \u00e0 distance \u00e0 tout moment pendant le processus de v\u00e9rification et l&rsquo;examen en ligne du candidat. Le flux est arr\u00eat\u00e9 \u00e0 la fin de l&rsquo;examen et le surveillant ne peut plus y acc\u00e9der.<\/p><p>Pendant le processus d&rsquo;examen en ligne, l&rsquo;application prend des captures d&rsquo;\u00e9cran automatiques toutes les 20 minutes \u00e0 partir du flux s\u00e9lectionn\u00e9 par le surveillant.\u00a0<\/p><p>Le surveillant \u00e0 distance compare le visage du candidat \u00e0 partir du flux de cam\u00e9ra en direct avec la pi\u00e8ce gouvernementale ou non gouvernementale qu&rsquo;il pr\u00e9sente au cours de la proc\u00e9dure de v\u00e9rification, et lorsqu&rsquo;une activit\u00e9 ou un comportement suspect contraire \u00e0 notre politique d&rsquo;examen est d\u00e9cel\u00e9 au cours de la proc\u00e9dure d&rsquo;examen.<\/p><p>Les donn\u00e9es provenant de la candidature \u00e0 l&rsquo;examen sont stock\u00e9es sur Amazon S3 Simple Storage Service et les compartiments sont par d\u00e9faut chiffr\u00e9s avec une cl\u00e9 de chiffrement AES-256 bits.<\/p><p>Les donn\u00e9es ne peuvent \u00eatre consult\u00e9es que si le personnel autoris\u00e9 de PECB et de l&rsquo;IAS en fait la demande, et ne sont pas partag\u00e9es avec d&rsquo;autres parties.<\/p><p>La p\u00e9riode de conservation des captures d&rsquo;\u00e9cran est de 3 ans.<\/p><h2><strong>8 Demande de certification<\/strong><\/h2><p>En tant qu&rsquo;organisme de certification, PECB est responsable de l&rsquo;\u00e9laboration et du maintien de certifications valides et \u00e0 jour, de l&rsquo;\u00e9tablissement des normes pour la certification de personnes et d\u2019organismes, ainsi que de la d\u00e9livrance des certificats.<\/p><p>Nous recueillons les informations personnelles des utilisateurs qui nous sont fournies \u00e0 partir de leur compte PECB. De plus, pour faire une demande de certification PECB, le candidat doit fournir des informations telles que son CV, son exp\u00e9rience de travail, ses \u00e9tudes et ses certifications.<\/p><p>Selon le programme de certification, vous devrez \u00e9galement fournir les coordonn\u00e9es de deux r\u00e9f\u00e9rences qui peuvent valider votre exp\u00e9rience professionnelle. Nous contacterons vos r\u00e9f\u00e9rences par e-mail ou par t\u00e9l\u00e9phone et elles seront invit\u00e9es \u00e0 remplir un formulaire en ligne pour confirmer l\u2019exp\u00e9rience du candidat.<\/p><h2><strong>9 Certification des formateurs<\/strong><\/h2><p>Les candidats int\u00e9ress\u00e9s par le processus de certification des formateurs de PECB doivent d&rsquo;abord soumettre le\u00a0<em>Formulaire d&rsquo;\u00e9ligibilit\u00e9 des formateurs PECB<\/em>\u00a0en utilisant leur compte PECB. De plus, il leur est demand\u00e9 de nous fournir un CV, le nom de leur soci\u00e9t\u00e9 et leur adresse. Une fois que PECB aura approuv\u00e9 l&rsquo;admissibilit\u00e9 du candidat \u00e0 devenir un formateur PECB, le formulaire de demande de certification de formateur sera disponible dans le compte PECB du candidat.<\/p><p>Au cours du processus de certification, les candidats sont tenus d&rsquo;envoyer \u00e9lectroniquement une vid\u00e9o d&rsquo;eux-m\u00eames simulant une prestation d&rsquo;une formation PECB. Cette s\u00e9ance d&rsquo;enregistrement se fait sur le site Web de PECB en utilisant l&rsquo;outil d&rsquo;enregistrement de PECB. La s\u00e9ance enregistr\u00e9e sera examin\u00e9e au cours du processus d&rsquo;\u00e9valuation du formateur.<\/p><p>Une fois la proc\u00e9dure de candidature du formateur termin\u00e9e, les informations et les donn\u00e9es des candidats dont la candidature est rejet\u00e9e sont conserv\u00e9es pendant un an, puis supprim\u00e9es de mani\u00e8re permanente. Toutefois, pour les candidats qui deviennent des formateurs certifi\u00e9s PECB, toutes les informations et les donn\u00e9es soumises durant la demande seront conserv\u00e9es par PECB. Si le statut du formateur est celui Freelancer (ind\u00e9pendant) ou Open with authorization (Ouvert avec autorisation), les informations seront rendues publiques sous l&rsquo;onglet Formateurs du site Web de PECB. Les donn\u00e9es ne seront pas partag\u00e9es avec des tiers \u00e0 moins que la loi ne l&rsquo;exige.<\/p><p>Les profils des formateurs agr\u00e9\u00e9s PECB sont \u00e9galement visibles sur les comptes des distributeurs PECB.<\/p><h2><strong>10 Demande de statut de surveillant<\/strong><\/h2><p>Les candidats int\u00e9ress\u00e9s \u00e0 devenir surveillants PECB doivent compl\u00e9ter leur demande en remplissant le formulaire d\u2019inscription avec leurs donn\u00e9es personnelles qui comprennent leurs nom complet, document d&rsquo;identification national, adresse e-mail, num\u00e9ro de t\u00e9l\u00e9phone, pays, r\u00e9gion et code postal.<\/p><p>Les donn\u00e9es personnelles sont utilis\u00e9es uniquement aux fins de surveillance et ne sont accessibles qu\u2019au partenaire qui a d\u00e9sign\u00e9 le surveillant.<\/p><p>La p\u00e9riode de conservation de la candidature du surveillant, y compris de la pi\u00e8ce d&rsquo;identit\u00e9, est de 3 ans \u00e0 compter de la date de la candidature.<\/p><h2><strong>11 Enfants<\/strong><\/h2><p>Cette d\u00e9claration de protection de la vie priv\u00e9e n&rsquo;est pas destin\u00e9e aux enfants. Nous comprenons l&rsquo;importance de prot\u00e9ger les donn\u00e9es des enfants, en particulier dans un environnement en ligne, et nous ne recueillons pas ou ne conservons pas sciemment des donn\u00e9es d\u2019enfants.<\/p><h2><strong>12 Moteurs de recherche<\/strong><\/h2><p>PECB se r\u00e9serve le droit de mettre en place sur son site Web un moteur de recherche afin d\u2019aider ses visiteurs \u00e0 trouver facilement des informations. Le moteur de recherche sera utilis\u00e9 pour rechercher des informations accessibles au public pr\u00e9sent\u00e9es sur notre site Web, et non les donn\u00e9es \u00e0 caract\u00e8re personnel de nos utilisateurs.<\/p><h2><strong>13 S\u00e9curit\u00e9 et performance<\/strong><\/h2><p>Nous prenons des pr\u00e9cautions pour prot\u00e9ger vos donn\u00e9es et votre vie priv\u00e9e. Lorsque vous soumettez des donn\u00e9es dans les formulaires disponibles sur notre site Web, vos donn\u00e9es sont prot\u00e9g\u00e9es en ligne et hors ligne. Seuls les employ\u00e9s qui ont besoin de l&rsquo;information pour effectuer un travail sp\u00e9cifique (par exemple, les responsables du service \u00e0 la client\u00e8le, les responsables de la certification et les \u00e9valuateurs) ont acc\u00e8s aux donn\u00e9es \u00e0 caract\u00e8re personnel. Les ordinateurs et serveurs dans lesquels nous stockons les donn\u00e9es \u00e0 caract\u00e8re personnel sont conserv\u00e9s dans un environnement s\u00e9curis\u00e9, surveill\u00e9, avec un acc\u00e8s strictement contr\u00f4l\u00e9.<\/p><p>Nous faisons appel \u00e0 un service fourni par un tiers pour aider \u00e0 maintenir la s\u00e9curit\u00e9 et la performance de notre site Web. \u00c9tant donn\u00e9 que les donn\u00e9es \u00e9chang\u00e9es par Internet ne sont pas s\u00e9curis\u00e9es \u00e0 100 %, nous ne pouvons pas garantir que les donn\u00e9es que vous envoyez ne seront pas perdues, utilis\u00e9es ill\u00e9galement ou modifi\u00e9es de mani\u00e8re frauduleuse. Nous n&rsquo;assumons aucune responsabilit\u00e9 quant \u00e0 l&rsquo;utilisation des donn\u00e9es par vous ou par un tiers.<\/p><h3><strong>13.1 R\u00e9tention des donn\u00e9es<\/strong><\/h3><p>Nous ne conservons les donn\u00e9es personnelles qu&rsquo;aussi longtemps que n\u00e9cessaire et uniquement pour les raisons \u00e9nonc\u00e9es dans la pr\u00e9sente d\u00e9claration, ou jusqu&rsquo;\u00e0 ce que nous recevions votre demande de suppression de vos donn\u00e9es personnelles. Veuillez noter que nous pouvons conserver vos donn\u00e9es pendant des p\u00e9riodes plus longues si n\u00e9cessaire pour nous conformer \u00e0 nos obligations l\u00e9gales.<\/p><h3><strong>13.2 Politique de protection des donn\u00e9es<\/strong><\/h3><p>PECB a \u00e9tabli une\u00a0<em>Politique de protection des donn\u00e9e<\/em>s qui garantit \u00e0 ses employ\u00e9s, clients, partenaires et intervenants que leurs donn\u00e9es sont prot\u00e9g\u00e9es et g\u00e9r\u00e9es avec soin et discr\u00e9tion. Veuillez lire notre Politique de protection des donn\u00e9es\u00a0<a href=\"https:\/\/pecb.com\/fr\/data-protection-policy\">ici<\/a>.<\/p><h2><strong>14 Plaintes<\/strong><\/h2><p>PECB s&rsquo;efforce de respecter les normes les plus \u00e9lev\u00e9es en mati\u00e8re de collecte et d&rsquo;utilisation des donn\u00e9es personnelles. C&rsquo;est pourquoi nous prenons au s\u00e9rieux les plaintes que nous recevons. Nous encourageons les utilisateurs de notre site Web, les visiteurs et toute partie int\u00e9ress\u00e9e \u00e0 porter \u00e0 notre attention toute observation ou opinion qui est consid\u00e9r\u00e9e comme indiquant une collecte et\/ou une utilisation injuste, trompeuse ou inappropri\u00e9e des donn\u00e9es.<\/p><p>Cette d\u00e9claration de protection de la vie priv\u00e9e se veut concise et claire. Elle ne fournit pas de d\u00e9tails exhaustifs sur tous les aspects de la collecte et de l&rsquo;utilisation des donn\u00e9es personnelles par PECB. Toutefois, nous sommes \u00e0 votre disposition pour tout compl\u00e9ment d&rsquo;information ou explication.<\/p><p>Si vous souhaitez porter plainte au sujet de la fa\u00e7on dont nous avons trait\u00e9 vos donn\u00e9es personnelles, vous pouvez le faire en suivant les \u00e9tapes d\u00e9crites dans notre\u00a0<a href=\"https:\/\/pecb.com\/fr\/complaint-and-appeal-policy\">Politique de plainte et d&rsquo;appel<\/a>.<\/p><h2><strong>15 Droits d&rsquo;acc\u00e8s des personnes concern\u00e9es dans le cadre du RGPD UE<\/strong><\/h2><p>Si vous faites partie de l&rsquo;Union europ\u00e9enne (UE) ou de l&rsquo;Espace \u00e9conomique europ\u00e9en (EEE), ou si vous acc\u00e9dez au site \u00e0 partir de ces territoires, vous disposez des droits suivants en vertu du RGPD :<\/p><ul><li>Droit d&rsquo;acc\u00e8s \u00e0 vos donn\u00e9es personnelles<\/li><li>Droit de corriger toute donn\u00e9e personnelle inexacte<\/li><li>Droit d&rsquo;effacer vos donn\u00e9es personnelles<\/li><li>Droit d&rsquo;opposition au traitement des donn\u00e9es personnelles<\/li><\/ul><p>Pour exercer vos droits en vertu du RGDP, vous pouvez envoyer une demande d&rsquo;acc\u00e8s aux donn\u00e9es personnelles \u00e0 notre d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es \u00e0 l&rsquo;adresse information.security@pecb.com. Nous v\u00e9rifierons toujours l&rsquo;identit\u00e9 de toute personne faisant une demande d&rsquo;acc\u00e8s \u00e0 une personne concern\u00e9e avant de lui remettre toute information. Une confirmation sera demand\u00e9e \u00e0 la personne concern\u00e9e en utilisant l&rsquo;adresse e-mail qu&rsquo;elle a utilis\u00e9e pour cr\u00e9er son compte PECB.<\/p><p>La premi\u00e8re copie de vos donn\u00e9es vous sera fournie gratuitement. Cependant, la personne concern\u00e9e devra payer des frais de 30 $ si elle demande d&rsquo;autres copies. Nous nous efforcerons de fournir les donn\u00e9es pertinentes dans un d\u00e9lai de 14 jours.<\/p><h3><strong>15.1 Demande d&rsquo;effacement<\/strong><\/h3><p>Lorsque vous soumettez une demande d&rsquo;effacement de vos donn\u00e9es, nous rendons anonymes toutes les informations personnelles de mani\u00e8re \u00e0 ce que la personne concern\u00e9e ne soit pas identifi\u00e9e. Les donn\u00e9es anonymis\u00e9es ne sont utilis\u00e9es par PECB qu&rsquo;\u00e0 des fins analytiques, comme le nombre de participants \u00e0 une formation ou le nombre de personnes certifi\u00e9es pour une certaine p\u00e9riode.<\/p><p>Veuillez garder \u00e0 l&rsquo;esprit que nous n&rsquo;effa\u00e7ons pas toutes vos informations en raison d&rsquo;obligations l\u00e9gales telles que les transactions financi\u00e8res et les exigences d&rsquo;accr\u00e9ditation. Si vous \u00eates certifi\u00e9 PECB et que vous d\u00e9tenez l\u2019une des certifications professionnelles que nous offrons et que vous demandez l&rsquo;effacement de vos donn\u00e9es personnelles, une copie num\u00e9rique des certificats et des factures sera stock\u00e9e et crypt\u00e9e avec un acc\u00e8s limit\u00e9.<\/p><h3><strong>15.2 D\u00e9sinscription des communications de marketing<\/strong><\/h3><p>Si vous d\u00e9cidez de vous d\u00e9sabonner de l\u2019envoi d\u2019e-mails de marketing, votre adresse e-mail sera retir\u00e9e de la liste de diffusion jusqu&rsquo;\u00e0 ce que vous d\u00e9cidiez volontairement de mettre \u00e0 jour vos pr\u00e9f\u00e9rences d&rsquo;abonnement.<\/p><p>Lors de votre d\u00e9sinscription, si vous d\u00e9cidez de conserver un compte PECB, vous continuerez \u00e0 recevoir des e-mails du syst\u00e8me PECB relatifs au param\u00e9trage de votre compte, \u00e0 la formation, \u00e0 l&rsquo;examen et \u00e0 la certification.<\/p><p>Pour vous d\u00e9sabonner des e-mails de marketing de PECB Group, cliquez sur le lien \u00ab Se d\u00e9sabonner \u00bb plac\u00e9 en bas de page des e-mails que vous recevez, ou contactez\u00a0<a href=\"mailto:support@pecb.com\">support@pecb.com<\/a>\u00a0pour mettre \u00e0 jour vos pr\u00e9f\u00e9rences d&rsquo;abonnement.<\/p><h2><strong>16 Divulgation des donn\u00e9es personnelles<\/strong><\/h2><p>En g\u00e9n\u00e9ral et en toutes circonstances, nous ne divulguerons pas de donn\u00e9es personnelles sans consentement. Toutefois, si l&rsquo;organisme de r\u00e9glementation, l&rsquo;autorit\u00e9 de contr\u00f4le ou d&rsquo;autres autorit\u00e9s l\u00e9gales le requi\u00e8rent, nous pouvons \u00eatre amen\u00e9s \u00e0 divulguer vos donn\u00e9es.<\/p><h2><strong>17 Modifications de cette d\u00e9claration de protection de la vie priv\u00e9e<\/strong><\/h2><p>Nous r\u00e9visons r\u00e9guli\u00e8rement cette d\u00e9claration de protection de la vie priv\u00e9e. Vous ne serez pas inform\u00e9 des modifications apport\u00e9es \u00e0 la pr\u00e9sente d\u00e9claration de protection de la vie priv\u00e9e. Vous \u00eates tenu de consulter cette d\u00e9claration sur notre site Web.<\/p><h3><strong>17.1 Comment nous contacter ?<\/strong><\/h3><p>Si vous souhaitez obtenir des informations sur notre d\u00e9claration de protection de la vie priv\u00e9e, vous pouvez nous envoyer un e-mail \u00e0\u00a0<a href=\"mailto:information.security@pecb.com\">information.security@pecb.com<\/a>\u00a0ou \u00e9crire \u00e0 notre si\u00e8ge :<\/p><p>Si\u00e8ge social de PECB<\/p><p>336-6683 Jean-Talon Est,\u00a0<\/p><p>Montr\u00e9al (Qu\u00e9bec)\u00a0 H1S 0A5\u00a0<\/p><p>CANADA<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u00e9claration de protection de la vie priv\u00e9e \u00a0 Derni\u00e8re mise \u00e0 jour le 16 septembre 2024. 1 Introduction PECB respecte le droit \u00e0 la protection de la vie priv\u00e9e de chaque visiteur du site. Nous recueillons et utilisons l&rsquo;information de nos sites Web uniquement comme mentionn\u00e9 dans la pr\u00e9sente d\u00e9claration de protection de la vie [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-27586","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9claration de protection de la vie priv\u00e9e - PECB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pecb.com\/fr\/pecb-privacy-statement\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9claration de protection de la vie priv\u00e9e - PECB\" \/>\n<meta property=\"og:description\" content=\"D\u00e9claration de protection de la vie priv\u00e9e \u00a0 Derni\u00e8re mise \u00e0 jour le 16 septembre 2024. 1 Introduction PECB respecte le droit \u00e0 la protection de la vie priv\u00e9e de chaque visiteur du site. Nous recueillons et utilisons l&rsquo;information de nos sites Web uniquement comme mentionn\u00e9 dans la pr\u00e9sente d\u00e9claration de protection de la vie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pecb.com\/fr\/pecb-privacy-statement\" \/>\n<meta property=\"og:site_name\" content=\"PECB\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PECBInternational\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-14T20:16:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PECB\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"28 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pecb.com\\\/fr\\\/pecb-privacy-statement\",\"url\":\"https:\\\/\\\/pecb.com\\\/fr\\\/pecb-privacy-statement\",\"name\":\"D\u00e9claration de protection de la vie priv\u00e9e - PECB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pecb.com\\\/fr#website\"},\"datePublished\":\"2025-08-13T11:40:47+00:00\",\"dateModified\":\"2025-08-14T20:16:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pecb.com\\\/fr\\\/pecb-privacy-statement#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pecb.com\\\/fr\\\/pecb-privacy-statement\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pecb.com\\\/fr\\\/pecb-privacy-statement#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pecb.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9claration de protection de la vie priv\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pecb.com\\\/fr#website\",\"url\":\"https:\\\/\\\/pecb.com\\\/fr\",\"name\":\"PECB\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pecb.com\\\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pecb.com\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pecb.com\\\/fr#organization\",\"name\":\"PECB\",\"url\":\"https:\\\/\\\/pecb.com\\\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pecb.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pecb.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Clip-path-group.svg\",\"contentUrl\":\"https:\\\/\\\/pecb.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Clip-path-group.svg\",\"width\":96,\"height\":26,\"caption\":\"PECB\"},\"image\":{\"@id\":\"https:\\\/\\\/pecb.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PECBInternational\\\/\",\"https:\\\/\\\/x.com\\\/PECB\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pecb\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCQPfrnIUa7Q0oBRyT8l5eTg\",\"https:\\\/\\\/www.instagram.com\\\/pecb.official\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9claration de protection de la vie priv\u00e9e - PECB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pecb.com\/fr\/pecb-privacy-statement","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9claration de protection de la vie priv\u00e9e - PECB","og_description":"D\u00e9claration de protection de la vie priv\u00e9e \u00a0 Derni\u00e8re mise \u00e0 jour le 16 septembre 2024. 1 Introduction PECB respecte le droit \u00e0 la protection de la vie priv\u00e9e de chaque visiteur du site. Nous recueillons et utilisons l&rsquo;information de nos sites Web uniquement comme mentionn\u00e9 dans la pr\u00e9sente d\u00e9claration de protection de la vie [&hellip;]","og_url":"https:\/\/pecb.com\/fr\/pecb-privacy-statement","og_site_name":"PECB","article_publisher":"https:\/\/www.facebook.com\/PECBInternational\/","article_modified_time":"2025-08-14T20:16:16+00:00","twitter_card":"summary_large_image","twitter_site":"@PECB","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"28 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pecb.com\/fr\/pecb-privacy-statement","url":"https:\/\/pecb.com\/fr\/pecb-privacy-statement","name":"D\u00e9claration de protection de la vie priv\u00e9e - PECB","isPartOf":{"@id":"https:\/\/pecb.com\/fr#website"},"datePublished":"2025-08-13T11:40:47+00:00","dateModified":"2025-08-14T20:16:16+00:00","breadcrumb":{"@id":"https:\/\/pecb.com\/fr\/pecb-privacy-statement#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pecb.com\/fr\/pecb-privacy-statement"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pecb.com\/fr\/pecb-privacy-statement#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pecb.com\/fr"},{"@type":"ListItem","position":2,"name":"D\u00e9claration de protection de la vie priv\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/pecb.com\/fr#website","url":"https:\/\/pecb.com\/fr","name":"PECB","description":"","publisher":{"@id":"https:\/\/pecb.com\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pecb.com\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/pecb.com\/fr#organization","name":"PECB","url":"https:\/\/pecb.com\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pecb.com\/fr#\/schema\/logo\/image\/","url":"https:\/\/pecb.com\/wp-content\/uploads\/2025\/05\/Clip-path-group.svg","contentUrl":"https:\/\/pecb.com\/wp-content\/uploads\/2025\/05\/Clip-path-group.svg","width":96,"height":26,"caption":"PECB"},"image":{"@id":"https:\/\/pecb.com\/fr#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PECBInternational\/","https:\/\/x.com\/PECB","https:\/\/www.linkedin.com\/company\/pecb","https:\/\/www.youtube.com\/channel\/UCQPfrnIUa7Q0oBRyT8l5eTg","https:\/\/www.instagram.com\/pecb.official\/"]}]}},"_links":{"self":[{"href":"https:\/\/pecb.com\/fr\/wp-json\/wp\/v2\/pages\/27586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pecb.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pecb.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pecb.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pecb.com\/fr\/wp-json\/wp\/v2\/comments?post=27586"}],"version-history":[{"count":0,"href":"https:\/\/pecb.com\/fr\/wp-json\/wp\/v2\/pages\/27586\/revisions"}],"wp:attachment":[{"href":"https:\/\/pecb.com\/fr\/wp-json\/wp\/v2\/media?parent=27586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}